{"id":13,"date":"2025-04-17T16:52:12","date_gmt":"2025-04-17T16:52:12","guid":{"rendered":"https:\/\/fast1herbal.co.id\/?page_id=13"},"modified":"2025-11-13T02:28:47","modified_gmt":"2025-11-13T02:28:47","slug":"lagalitas","status":"publish","type":"page","link":"https:\/\/fast1herbal.co.id\/en\/lagalitas\/","title":{"rendered":"Legality"},"content":{"rendered":"<div class=\"agwt-container\">\r\n    \r\n    <!-- Tabs Button -->\r\n    <div class=\"wt-tabs-btn-container246 wt-body-style\">\r\n        \t\t\t<a class=\"wt-btn246 wt-tabs-tb246 wt-tabs-top  active\"\r\n\t\t\t\t\t\t            style=\"cursor:pointer;\"\r\n\t\t\t\t\t\t            onclick=\"wtOpenTb(event,'wt-tab2461', '246', 'normal')\">\r\n\t\t\t\t\t\t            \t\t\t\t\t\t            <i class=\"\" id=\"wtOpen\"><\/i>\r\n\t\t\t\t\t\t                                                <div class=\"title_tag\">Identitas dan Legalitas Perusahaan<\/div>\r\n                    <\/a>\r\n\r\n        \t\t\t<a class=\"wt-btn246 wt-tabs-tb246 wt-tabs-top\"\r\n\t\t\t\t\t\t            style=\"cursor:pointer;\"\r\n\t\t\t\t\t\t            onclick=\"wtOpenTb(event,'wt-tab2462', '246', 'normal')\">\r\n\t\t\t\t\t\t            \t\t\t\t\t\t            <i class=\"\" id=\"wtOpen\"><\/i>\r\n\t\t\t\t\t\t                                                <div class=\"title_tag\">Surat Izin Industri Obat Tradisional<\/div>\r\n                    <\/a>\r\n\r\n        \t\t\t<a class=\"wt-btn246 wt-tabs-tb246 wt-tabs-top\"\r\n\t\t\t\t\t\t            style=\"cursor:pointer;\"\r\n\t\t\t\t\t\t            onclick=\"wtOpenTb(event,'wt-tab2463', '246', 'normal')\">\r\n\t\t\t\t\t\t            \t\t\t\t\t\t            <i class=\"\" id=\"wtOpen\"><\/i>\r\n\t\t\t\t\t\t                                                <div class=\"title_tag\">Sertifikat CPOTB\/GMP tanggal 28 Januari 2025 <\/div>\r\n                    <\/a>\r\n\r\n        \t\t\t<a class=\"wt-btn246 wt-tabs-tb246 wt-tabs-top\"\r\n\t\t\t\t\t\t            style=\"cursor:pointer;\"\r\n\t\t\t\t\t\t            onclick=\"wtOpenTb(event,'wt-tab2464', '246', 'normal')\">\r\n\t\t\t\t\t\t            \t\t\t\t\t\t            <i class=\"\" id=\"wtOpen\"><\/i>\r\n\t\t\t\t\t\t                                                <div class=\"title_tag\">Sertifikat Halal Obat Tradisional (OT) Produk PT FAST<\/div>\r\n                    <\/a>\r\n\r\n        \r\n    <\/div>\r\n    <!-- End Tabs Button -->\r\n\r\n\r\n        <!-- Tabs Body -->\r\n    <div class=\"wt-tabs-body wt-body246\">\r\n\r\n        \t\t\t\t\t\t        <!-- Start tabs-->\r\n\t\t\t<div class=\"wt-single-tab246\" id=\"wt-tab2461\"\r\n\t\t\t style=\"display:block;\" >\r\n<p style=\"text-align: left\">DEED OF ESTABLISHMENT : 09 April 2013 Number : 08<\/p>\r\n<p style=\"text-align: left\">FIRST AMENDMENT DEED: April 28, 2014 Number: 09.<\/p>\r\nBecoming a Traditional Medicine Industry (IOT)\n\nSK MENHUKHAM Number: AHU-27333.AH.01.01. Year 2013\r\n<table>\r\n<tbody>\r\n<tr>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-248 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/AKTA-PENDIRIAN-09-April-2013-Nomor-08-600x846-1-213x300.jpg\" alt=\"\" width=\"243\" height=\"342\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/AKTA-PENDIRIAN-09-April-2013-Nomor-08-600x846-1-213x300.jpg 213w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/AKTA-PENDIRIAN-09-April-2013-Nomor-08-600x846-1.jpg 600w\" sizes=\"auto, (max-width: 243px) 100vw, 243px\" \/><\/td>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-247 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/AKTE-PERUBAHAN-PERTAMA-28-April-2014-Nomor-09-768x1127-1-204x300.jpg\" alt=\"\" width=\"226\" height=\"333\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/AKTE-PERUBAHAN-PERTAMA-28-April-2014-Nomor-09-768x1127-1-204x300.jpg 204w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/AKTE-PERUBAHAN-PERTAMA-28-April-2014-Nomor-09-768x1127-1-698x1024.jpg 698w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/AKTE-PERUBAHAN-PERTAMA-28-April-2014-Nomor-09-768x1127-1.jpg 768w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" \/><\/td>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-249 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-213x300.jpg\" alt=\"\" width=\"238\" height=\"335\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-213x300.jpg 213w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-600x846.jpg 600w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-726x1024.jpg 726w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-768x1083.jpg 768w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM.jpg 867w\" sizes=\"auto, (max-width: 238px) 100vw, 238px\" \/><\/td>\r\n<\/tr>\r\n<tr>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-628 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/AKTA-PERUBAHAN-Nomor.-05-Tanggal-29-Mei-2024-212x300.jpg\" alt=\"\" width=\"228\" height=\"323\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/AKTA-PERUBAHAN-Nomor.-05-Tanggal-29-Mei-2024-212x300.jpg 212w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/AKTA-PERUBAHAN-Nomor.-05-Tanggal-29-Mei-2024.jpg 414w\" sizes=\"auto, (max-width: 228px) 100vw, 228px\" \/><\/td>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-629 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-Nomor-AHU-0031640AH0102Tahun-2024-1-196x300.jpg\" alt=\"\" width=\"212\" height=\"324\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-Nomor-AHU-0031640AH0102Tahun-2024-1-196x300.jpg 196w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-Nomor-AHU-0031640AH0102Tahun-2024-1.jpg 391w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/td>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-630 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-Nomor-AHU-0031640AH0102Tahun-2024-2-195x300.jpg\" alt=\"\" width=\"213\" height=\"328\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-Nomor-AHU-0031640AH0102Tahun-2024-2-195x300.jpg 195w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SK-MENHUKHAM-Nomor-AHU-0031640AH0102Tahun-2024-2.jpg 390w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><\/td>\r\n<\/tr>\r\n<tr>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-631 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/TDP-241x300.jpg\" alt=\"\" width=\"241\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/TDP-241x300.jpg 241w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/TDP.jpg 461w\" sizes=\"auto, (max-width: 241px) 100vw, 241px\" \/><\/td>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-632 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SIUP-265x300.jpg\" alt=\"\" width=\"265\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SIUP-265x300.jpg 265w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/SIUP.jpg 509w\" sizes=\"auto, (max-width: 265px) 100vw, 265px\" \/><\/td>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-633 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/NPWP-300x190.jpg\" alt=\"\" width=\"300\" height=\"190\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/NPWP-300x190.jpg 300w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/NPWP-600x379.jpg 600w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/NPWP.jpg 625w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/td>\r\n<\/tr>\r\n<tr>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-634 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/IUI-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/IUI-214x300.jpg 214w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/IUI.jpg 513w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/td>\r\n<td><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-635 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/NIB-188x300.jpg\" alt=\"\" width=\"243\" height=\"388\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/NIB-188x300.jpg 188w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/NIB.jpg 449w\" sizes=\"auto, (max-width: 243px) 100vw, 243px\" \/><\/td>\r\n<td><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>        <\/div>\r\n        <!-- End tabs -->\r\n        \r\n        \t\t\t\t\t\t        <!-- Start tabs-->\r\n\t\t\t<div class=\"wt-single-tab246\" id=\"wt-tab2462\"\r\n\t\t\t>\r\n<p style=\"text-align: center\"><b>Surat <\/b><b>Izin<\/b> <b>Industri<\/b> <b>Obat<\/b> <b>Tradisional<\/b><\/p>\n<p style=\"text-align: center\">Sertifikat Industri Obat Tradisional (IOT) melalui e-licensing mengikuti peraturan One Single Submission<\/p>\n<p style=\"text-align: center\">(OSS) Tanggal 24 Mei 2019 Nomor : FP.02.03 \/IV\/0400\/2019<\/p>\n<table>\n<tbody>\n<tr>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-636 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/Sertifikat-Industri-Obat-Tradisional-1-195x300.jpg\" alt=\"\" width=\"195\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/Sertifikat-Industri-Obat-Tradisional-1-195x300.jpg 195w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/Sertifikat-Industri-Obat-Tradisional-1.jpg 380w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/td>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-637 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/Sertifikat-Industri-Obat-Tradisional-2-195x300.jpg\" alt=\"\" width=\"195\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/Sertifikat-Industri-Obat-Tradisional-2-195x300.jpg 195w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/Sertifikat-Industri-Obat-Tradisional-2.jpg 380w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/td>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-638 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/Sertifikat-Industri-Obat-Tradisional-3-195x300.jpg\" alt=\"\" width=\"195\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/Sertifikat-Industri-Obat-Tradisional-3-195x300.jpg 195w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/Sertifikat-Industri-Obat-Tradisional-3.jpg 380w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n        <\/div>\r\n        <!-- End tabs -->\r\n        \r\n        \t\t\t\t\t\t        <!-- Start tabs-->\r\n\t\t\t<div class=\"wt-single-tab246\" id=\"wt-tab2463\"\r\n\t\t\t>\r\n<p style=\"text-align: center\"><strong>Sertifikat CPOTB\/GMP<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-640\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/kapsul-187x300.jpg\" alt=\"\" width=\"187\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/kapsul-187x300.jpg 187w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/kapsul.jpg 527w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/><\/td>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-639\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/tablet-185x300.jpg\" alt=\"\" width=\"185\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/tablet-185x300.jpg 185w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/tablet.jpg 518w\" sizes=\"auto, (max-width: 185px) 100vw, 185px\" \/><\/td>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-641\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/cod-189x300.jpg\" alt=\"\" width=\"189\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/cod-189x300.jpg 189w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/cod.jpg 525w\" sizes=\"auto, (max-width: 189px) 100vw, 189px\" \/><\/td>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-642\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/serbuk-185x300.jpg\" alt=\"\" width=\"185\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/serbuk-185x300.jpg 185w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/serbuk.jpg 512w\" sizes=\"auto, (max-width: 185px) 100vw, 185px\" \/><\/td>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-643\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/col-191x300.jpg\" alt=\"\" width=\"191\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/col-191x300.jpg 191w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/col.jpg 522w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n        <\/div>\r\n        <!-- End tabs -->\r\n        \r\n        \t\t\t\t\t\t        <!-- Start tabs-->\r\n\t\t\t<div class=\"wt-single-tab246\" id=\"wt-tab2464\"\r\n\t\t\t>\r\n<p>Sertifikat Halal Obat Tradisional (OT) Produk PT FAST<\/p>\n<p>OBAT TRADISIONAL<\/p>\n<table>\n<tbody>\n<tr>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-826 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/1-3-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/1-3-212x300.jpg 212w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/1-3-8x12.jpg 8w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/1-3.jpg 394w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/td>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-827 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/2-3-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/2-3-212x300.jpg 212w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/2-3-8x12.jpg 8w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/2-3.jpg 393w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/td>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-828 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/3-2-213x300.jpg\" alt=\"\" width=\"213\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/3-2-213x300.jpg 213w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/3-2-9x12.jpg 9w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/3-2.jpg 391w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-829 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/4-1-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/4-1-212x300.jpg 212w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/4-1-8x12.jpg 8w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/4-1.jpg 405w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/td>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-830 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/5-1-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/5-1-212x300.jpg 212w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/5-1-8x12.jpg 8w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/5-1.jpg 405w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>SUPLEMENT<\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-831 aligncenter\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/6-1-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/6-1-212x300.jpg 212w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/6-1-8x12.jpg 8w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/6-1.jpg 402w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/td>\n<td><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-832 alignnone\" src=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/7-1-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/7-1-212x300.jpg 212w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/7-1-8x12.jpg 8w, https:\/\/fast1herbal.co.id\/wp-content\/uploads\/2025\/04\/7-1.jpg 402w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n        <\/div>\r\n        <!-- End tabs -->\r\n        \r\n        \r\n    <\/div>\r\n    <!-- End Tabs Body -->\r\n    <\/div>\r\n<style>\r\n     *,\r\n\t*::before,\r\n\t*::after {\r\n\t  box-sizing: border-box;\r\n\t}\r\n\r\n\t        .agwt-container { max-width:inherit; }\r\n\t\r\n\t\t\t.agwt-container .normal_content_section_title_246{ max-width:100% !important;}\r\n\t\t\t.agwt-container a {box-shadow:none}\r\n\t\t\t.agwt-container .normal_content_section_title_246 {margin-bottom:15px}\r\n\t\t\t.agwt-container a.wt-tabs-tb246 {\r\n\t\t\t\ttext-decoration: none !important;\r\n\t\t    }\r\n\t\t\t.agwt-container a.wt-tabs-tb246:hover {\r\n\t\t\t\ttext-decoration: none !important;\r\n\t\t\t}\r\n\r\n\t\t\t.agwt-container .normal_content_section_title_246 .section_title h1 {font-size: 2em !important; color:#000;}\r\n\t\t\t.agwt-container .normal_content_section_title_246 .section_title h2 {font-size: 1.5em !important; color:#000;}\r\n\t\t\t.agwt-container .normal_content_section_title_246 .section_title h3 {font-size: 1.17em !important; color:#000;}\r\n\t\t\t.agwt-container .normal_content_section_title_246 .section_title h4 {font-size: 1em !important; color:#000;}\r\n\t\t\t.agwt-container .normal_content_section_title_246 .section_title h5 {font-size: 0.83em !important; color:#000;}\r\n\t\t\t.agwt-container .normal_content_section_title_246 .section_title h6 {font-size: 0.67em !important; color:#000;}\r\n\t\t\t.agwt-container .normal_content_section_title_246 .section_title p  { color:#000;}\r\n\r\n\t\t\t.wt-tabs-tb246 {\r\n\t\t\t    float: left;\r\n\t\t\t    color:#000;\r\n\t\t\t    background: #eee;\r\n\t\t\t    border: 1px solid #ccc;\r\n\t\t\t}\r\n\r\n\t\t\t.wt-tabs-tb246.active {\r\n\t\t\t\tcolor:#000;\r\n\t\t\t\tbackground:#fff;\r\n\t\t\t}\r\n\r\n\t\t\t.wt-tabs-tb246:hover {\r\n\t\t\t\tcolor:#000;\r\n\t\t\t\tbackground:#fff;\r\n\t\t\t}\r\n\r\n\t\t\t.child-class { \r\n\t\t\t\tflex-direction: column;\r\n\t\t\t\twidth: 25%;\r\n\t\t\t\tpadding-right:10px;\r\n\t\t\t}\r\n\r\n\t\t\t.child-class-menu {  display:inline-block; }\r\n\r\n\t\t\t.child-class .wt-tabs-tb246 i {\r\n\t\t\t\tfloat:left;\r\n\t\t\t}\r\n\r\n\t\t\t.wt-single-nest-tab246 {\r\n\t\t\t\tdisplay: none;\r\n\t\t\t}\r\n\r\n\t\t\t.nested-type .wt-tabs-body.wt-body246 {\r\n\t\t\t\tpadding-left:2px;\r\n\t\t\t\tpadding-top:5px;\r\n\r\n\t\t\t}\r\n\r\n\t\t\t.child-class-body {\r\n\t\t\t\twidth: inherit;\r\n\t\t\t\toverflow: hidden;\r\n\t\t\t}\r\n\r\n\t\t\t.wt-tabs-tb246 i {\r\n\t\t\t\tcolor:#000;\r\n\t\t\t    margin-right:1px;\r\n\t\t\t\tfont-size:20px;\r\n\t\t\t\tline-height:1.6;\r\n\t\t\t}\r\n\r\n\t\t\t.wt-tabs-tb246 img {\r\n\t\t\t\tdisplay:inline-block;\r\n\t\t\t\tmargin-top:5px;\r\n\t\t\t\tmargin-right:1px;\r\n\t\t\t  }\r\n\r\n\t\t\t.wt-tabs-tb246.active i {\r\n\t\t\t\tcolor:#000;\r\n\t\t\t}\r\n\r\n\t\t\t.wt-tabs-tb246:hover i {\r\n\t\t\t\tcolor:#000;\r\n\t\t\t}\r\n\r\n\t\t\t.title_tag {\r\n\t\t\t\tfont-size:20px;\r\n\t\t\t\tfloat:right;\r\n\t\t\t}\r\n\r\n\t\t\t.wt-tabs-body.wt-body246 {\r\n\t\t\t\twidth:inherit;\r\n\t\t\t    background-color:#fff;\r\n\t\t\t    border:1px solid #ccc;\r\n\t\t\t    padding:20px 20px 20px 20px;\r\n\t\t\t}\r\n\t\t\t.agwt-container {\r\n\t\t\t    line-height: 1.6;\r\n\t\t\t}\r\n\r\n\t\t\t.tax-btn246:hover { background:#fff; }\r\n\t\t\t.tax-btn246.active { background:#fff; }\r\n\r\n\t\t\t.wt-single-tab246 {\r\n\t\t\t    display: none;\r\n\t\t\t}\r\n\t\t\t.wt-tabs-tb246 {\r\n\t\t\t\tpadding: 10px 10px 10px 10px;\r\n\t\t\t\tborder-radius:2px;\r\n\t\t\t}\r\n\r\n\t\t\t \r\n\t\t.agwt-container .normal_content_section_title_246 .section_title h1{ font-family:Poppins !important; } \r\n\t\t.agwt-container .normal_content_section_title_246 .section_title h2{ font-family:Poppins !important; } \r\n\t\t.agwt-container .normal_content_section_title_246 .section_title h3{ font-family:Poppins !important; } \r\n\t\t.agwt-container .normal_content_section_title_246 .section_title h4{ font-family:Poppins !important; } \r\n\t\t.agwt-container .normal_content_section_title_246 .section_title h5{ font-family:Poppins !important; } \r\n\t\t.agwt-container .normal_content_section_title_246 .section_title h6{ font-family:Poppins !important; } \r\n\t\t.agwt-container .normal_content_section_title_246 .section_title p{ font-family:Poppins !important; } \r\n\t\t\r\n\t\t.agwt-container .wt-body .wt-single-tab h1,\r\n\t\t\t\t\t\t\t\t\t.agwt-container .wt-body .wt-single-tab h2,\r\n\t\t\t\t\t\t\t\t\t.agwt-container .wt-body .wt-single-tab h3,\r\n\t\t\t\t\t\t\t\t\t.agwt-container .wt-body .wt-single-tab h4,\r\n\t\t\t\t\t\t\t\t\t.agwt-container .wt-body .wt-single-tab h5,\r\n\t\t\t\t\t\t\t\t\t.agwt-container .wt-body .wt-single-tab h6,\r\n\t\t\t\t\t\t\t\t\t.agwt-container .wt-body .wt-single-tab p, .agwt-container {\r\n\t\t\t\t\t\t\t\t\t    font-family:Poppins !important;\r\n\t\t\t\t\t\t\t\t\t    font-weight:normal !important;\r\n\t\t\t\t\t\t\t\t\t    font-style:normal !important;\r\n\t\t\t\t\t\t\t\t\t}\r\n\r\n\t\t\t\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t           .wt-btn246.active {\r\n\t\t\t\t\t\t\t\t\t    border-color: #ccc #ccc transparent;\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t.tax-btn246.active {\r\n\t\t\t\t\t\t\t\t\t    border-color: #ccc #ccc transparent;\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t .wt-tabs-btn-container246 {\r\n\t\t\t\t\t\t\t\t\t    left: 0%;\r\n\t\t\t\t\t\t\t\t\t    display: flex;\r\n\t\t\t\t\t\t\t\t\t    padding-top: 0px;\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t.agwt-container a.wt-tabs-tb246 {\r\n\t\t\t\t\t\t\t\t\t\tmargin-bottom: -1px;\r\n\t\t\t\t\t\t\t\t\t}\r\n\r\n\t\t\t\t\t\t\t\t\t.wt-tabs-btn-container246.active { border-bottom:none; }\r\n\r\n\t\t\t\t\t\t\t\t\t.wt-tabs-tb246 {\r\n\t\t\t\t\t\t\tmargin: 0px 0px 0px 0px;\r\n\t\t\t\t\t\t\t}@media only screen and (max-width: 668px) {\r\n\t\t\t    .wt-tabs-btn-container246 {\r\n\t\t\t        flex-flow:column;\r\n\t\t\t    }\r\n\t\t\t}<\/style>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fast1herbal.co.id\/en\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fast1herbal.co.id\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fast1herbal.co.id\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fast1herbal.co.id\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fast1herbal.co.id\/en\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":4,"href":"https:\/\/fast1herbal.co.id\/en\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"predecessor-version":[{"id":905,"href":"https:\/\/fast1herbal.co.id\/en\/wp-json\/wp\/v2\/pages\/13\/revisions\/905"}],"wp:attachment":[{"href":"https:\/\/fast1herbal.co.id\/en\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}